{"id":137543,"date":"2023-08-24T09:58:29","date_gmt":"2023-08-24T09:58:29","guid":{"rendered":"https:\/\/kunstboer.com\/?post_type=product&#038;p=137543"},"modified":"2024-09-16T19:49:17","modified_gmt":"2024-09-16T19:49:17","slug":"sac-a-dos-chat-avec-lunettes-kopie-kopie","status":"publish","type":"product","link":"https:\/\/kunstboer.com\/fr\/produit\/sac-a-dos-chat-avec-lunettes-kopie-kopie\/","title":{"rendered":"Cac \u00e0 dos Chat espace"},"content":{"rendered":"<p><span class=\"Y2IQFc\" lang=\"fr\">Sac \u00e0 dos tr\u00e8s pratique pour l&#8217;\u00e9cole, le sport, les week-ends et les nuit\u00e9es. Bretelles extra longues avec renforts aux points d&#8217;attache. <\/span><\/p>\n<ul>\n<li><span class=\"Y2IQFc\" lang=\"fr\">35x25x15 cm <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Bretelles ergonomiques l\u00e9g\u00e8rement rembourr\u00e9es, renforc\u00e9es de nylon <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Points de fixation renforc\u00e9s de nylon <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Poids 350 grammes <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Boucle de suspension au dos <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Fermeture \u00e9clair de la couleur du sac en haut <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Facile \u00e0 nettoyer <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Plaque de base en plastique renforc\u00e9 <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Grande poche avant avec fermeture \u00e9clair 25 x 23 x 5 cm<\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Poche portefeuille avec fermeture \u00e9clair \u00e0 l&#8217;int\u00e9rieur<\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Porte-gobelet avec \u00e9lastique \u00e0 l&#8217;int\u00e9rieur Pare-chocs (passepoil) tout autour <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Int\u00e9rieur fini en nylon, facile \u00e0 nettoyer <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Exp\u00e9di\u00e9 rapidement et en toute s\u00e9curit\u00e9 par Kunstboer <\/span><\/li>\n<li><span class=\"Y2IQFc\" lang=\"fr\">Garantie constructeur 1 an<\/span><\/li>\n<\/ul>\n<script language='javascript' type='text\/javascript'>function getWR360PopupSkin(){return 'light_clean';}<\/script>","protected":false},"excerpt":{"rendered":"<p>Sac \u00e0 dos tr\u00e8s pratique pour l&#8217;\u00e9cole, le sport, les week-ends et les nuit\u00e9es. Bretelles extra longues avec renforts aux points d&#8217;attache. 35x25x15 cm Bretelles ergonomiques l\u00e9g\u00e8rement rembourr\u00e9es, renforc\u00e9es de nylon Points de fixation renforc\u00e9s de nylon Poids 350 grammes Boucle de suspension au dos Fermeture \u00e9clair de la couleur du sac en haut Facile [&hellip;]<\/p>\n","protected":false},"featured_media":138203,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[730],"product_tag":[],"class_list":{"0":"post-137543","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-tassen-fr","8":"first","9":"instock","10":"taxable","11":"shipping-taxable","12":"purchasable","13":"product-type-simple"},"composite_virtual":false,"composite_layout":"","composite_add_to_cart_form_location":"","composite_editable_in_cart":false,"composite_sold_individually_context":"","composite_shop_price_calc":"","composite_components":[],"composite_scenarios":[],"bundled_by":[],"bundle_stock_status":"instock","bundle_stock_quantity":10,"bundle_virtual":false,"bundle_layout":"","bundle_add_to_cart_form_location":"","bundle_editable_in_cart":false,"bundle_sold_individually_context":"","bundle_item_grouping":"","bundle_min_size":"","bundle_max_size":"","bundle_price":[],"bundled_items":[],"bundle_sell_ids":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Cac \u00e0 dos Chat espace | Kunstboer<\/title>\n<meta name=\"description\" content=\"sac \u00e0 dos chat avec lunettes, Vous cherchez un joli sac \u00e0 dos pour enfant ? Avec le sac \u00e0 dos chat. achetez un sac \u00e0 dos pour chat, avec ce sac \u00e0 dos de Kunstboer, vous volez la vedette ! Ce sac \u00e0 dos solide, design chat.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Cac \u00e0 dos Chat espace | Kunstboer\" \/>\n<meta property=\"og:description\" content=\"sac \u00e0 dos chat avec lunettes, Vous cherchez un joli sac \u00e0 dos pour enfant ? Avec le sac \u00e0 dos chat. achetez un sac \u00e0 dos pour chat, avec ce sac \u00e0 dos de Kunstboer, vous volez la vedette ! Ce sac \u00e0 dos solide, design chat.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/\" \/>\n<meta property=\"og:site_name\" content=\"Kunstboer\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-16T19:49:17+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"1000\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/\",\"url\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/\",\"name\":\"Cac \u00e0 dos Chat espace | Kunstboer\",\"isPartOf\":{\"@id\":\"https:\/\/kunstboer.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg\",\"datePublished\":\"2023-08-24T09:58:29+00:00\",\"dateModified\":\"2024-09-16T19:49:17+00:00\",\"description\":\"sac \u00e0 dos chat avec lunettes, Vous cherchez un joli sac \u00e0 dos pour enfant ? Avec le sac \u00e0 dos chat. achetez un sac \u00e0 dos pour chat, avec ce sac \u00e0 dos de Kunstboer, vous volez la vedette ! Ce sac \u00e0 dos solide, design chat.\",\"breadcrumb\":{\"@id\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#primaryimage\",\"url\":\"https:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg\",\"contentUrl\":\"https:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/kunstboer.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"E-Boutique\",\"item\":\"https:\/\/kunstboer.com\/shop\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cac \u00e0 dos Chat espace\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/kunstboer.com\/#website\",\"url\":\"https:\/\/kunstboer.com\/\",\"name\":\"Kunstboer\",\"description\":\"Kleurrijk en verrassend merk\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/kunstboer.com\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Cac \u00e0 dos Chat espace | Kunstboer","description":"sac \u00e0 dos chat avec lunettes, Vous cherchez un joli sac \u00e0 dos pour enfant ? Avec le sac \u00e0 dos chat. achetez un sac \u00e0 dos pour chat, avec ce sac \u00e0 dos de Kunstboer, vous volez la vedette ! Ce sac \u00e0 dos solide, design chat.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/","og_locale":"fr_FR","og_type":"article","og_title":"Cac \u00e0 dos Chat espace | Kunstboer","og_description":"sac \u00e0 dos chat avec lunettes, Vous cherchez un joli sac \u00e0 dos pour enfant ? Avec le sac \u00e0 dos chat. achetez un sac \u00e0 dos pour chat, avec ce sac \u00e0 dos de Kunstboer, vous volez la vedette ! Ce sac \u00e0 dos solide, design chat.","og_url":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/","og_site_name":"Kunstboer","article_modified_time":"2024-09-16T19:49:17+00:00","og_image":[{"width":1000,"height":1000,"url":"http:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/","url":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/","name":"Cac \u00e0 dos Chat espace | Kunstboer","isPartOf":{"@id":"https:\/\/kunstboer.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#primaryimage"},"image":{"@id":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#primaryimage"},"thumbnailUrl":"https:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg","datePublished":"2023-08-24T09:58:29+00:00","dateModified":"2024-09-16T19:49:17+00:00","description":"sac \u00e0 dos chat avec lunettes, Vous cherchez un joli sac \u00e0 dos pour enfant ? Avec le sac \u00e0 dos chat. achetez un sac \u00e0 dos pour chat, avec ce sac \u00e0 dos de Kunstboer, vous volez la vedette ! Ce sac \u00e0 dos solide, design chat.","breadcrumb":{"@id":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/kunstboer.com\/product\/rugzak-space-katten\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#primaryimage","url":"https:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg","contentUrl":"https:\/\/kunstboer.com\/wp-content\/uploads\/2023\/08\/xx037v.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/kunstboer.com\/product\/rugzak-space-katten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/kunstboer.com\/fr\/"},{"@type":"ListItem","position":2,"name":"E-Boutique","item":"https:\/\/kunstboer.com\/shop\/"},{"@type":"ListItem","position":3,"name":"Cac \u00e0 dos Chat espace"}]},{"@type":"WebSite","@id":"https:\/\/kunstboer.com\/#website","url":"https:\/\/kunstboer.com\/","name":"Kunstboer","description":"Kleurrijk en verrassend merk","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/kunstboer.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/product\/137543","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/comments?post=137543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/media\/138203"}],"wp:attachment":[{"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/media?parent=137543"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/product_brand?post=137543"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/product_cat?post=137543"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/kunstboer.com\/fr\/wp-json\/wp\/v2\/product_tag?post=137543"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}